{"id":14189,"date":"2026-05-13T01:58:27","date_gmt":"2026-05-13T01:58:27","guid":{"rendered":"https:\/\/www.detalpalonoticias.com.ar\/wp\/?p=14189"},"modified":"2026-05-13T01:58:27","modified_gmt":"2026-05-13T01:58:27","slug":"multitudinaria-marcha-universitaria-en-cordoba-mas-de-120-mil-personas-defendieron-la-educacion-publica","status":"publish","type":"post","link":"https:\/\/www.detalpalonoticias.com.ar\/wp\/multitudinaria-marcha-universitaria-en-cordoba-mas-de-120-mil-personas-defendieron-la-educacion-publica\/","title":{"rendered":"Multitudinaria marcha universitaria en C\u00f3rdoba: m\u00e1s de 120 mil personas defendieron la educaci\u00f3n p\u00fablica."},"content":{"rendered":"\n<p>La ciudad de C\u00f3rdoba volvi\u00f3 a ser escenario de una masiva movilizaci\u00f3n en defensa de las universidades p\u00fablicas. M\u00e1s de 120 mil personas participaron este martes de la cuarta Marcha Federal Universitaria realizada durante el gobierno de Javier Milei.<\/p>\n\n\n\n<p>La convocatoria reuni\u00f3 a rectores, docentes, no docentes, estudiantes, gremios y organizaciones sociales que marcharon desde el Monumento a la Reforma hasta V\u00e9lez Sarsfield y Boulevard San Juan, reclamando mayor financiamiento para las universidades, recomposici\u00f3n salarial y el cumplimiento de la Ley de Financiamiento Universitario.<\/p>\n\n\n\n<p>Desde Adiuc se\u00f1alaron que el conflicto debe resolverse mediante una mesa de negociaci\u00f3n para discutir salarios y presupuesto, mientras que autoridades universitarias advirtieron sobre el fuerte deterioro econ\u00f3mico que atraviesa el sistema educativo superior.<\/p>\n\n\n\n<p>El rector de la UNC, Jhon Boretto, pidi\u00f3 que el Gobierno nacional \u201ccumpla con la ley y restablezca el presupuesto universitario\u201d, destacando adem\u00e1s el respaldo social que contin\u00faa teniendo la universidad p\u00fablica.<\/p>\n\n\n\n<p>Durante la jornada tambi\u00e9n se remarc\u00f3 la p\u00e9rdida del poder adquisitivo de docentes y no docentes, el ajuste sobre investigaci\u00f3n cient\u00edfica y la incertidumbre que atraviesan las casas de altos estudios de todo el pa\u00eds.<\/p>\n\n\n\n<p>La Ley de Financiamiento Universitario, aprobada por el Congreso y luego judicializada por el Gobierno nacional, qued\u00f3 ahora en manos de la Corte Suprema.<\/p>\n\n\n\n<p> \u201cLa universidad p\u00fablica es un bien muy preciado\u201d, fue una de las frases que m\u00e1s se repiti\u00f3 en una jornada marcada por la defensa de la educaci\u00f3n y el reclamo por mayor inversi\u00f3n estatal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de C\u00f3rdoba volvi\u00f3 a ser escenario de una masiva movilizaci\u00f3n en defensa de las universidades p\u00fablicas. M\u00e1s de 120 mil personas participaron este martes de la cuarta Marcha&hellip;<\/p>\n","protected":false},"author":4,"featured_media":14190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.detalpalonoticias.com.ar\/wp\/wp-content\/uploads\/2026\/05\/MARCHA-UNI.webp?fit=1005%2C666&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/posts\/14189"}],"collection":[{"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/comments?post=14189"}],"version-history":[{"count":2,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/posts\/14189\/revisions"}],"predecessor-version":[{"id":14192,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/posts\/14189\/revisions\/14192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/media\/14190"}],"wp:attachment":[{"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/media?parent=14189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/categories?post=14189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.detalpalonoticias.com.ar\/wp\/wp-json\/wp\/v2\/tags?post=14189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}